{"id":344273,"date":"2020-05-27T00:00:00","date_gmt":"2020-05-26T22:00:00","guid":{"rendered":"https:\/\/www.fiarebancaetica.coop\/eina-cooperativa-temps-lliure-transformador\/"},"modified":"2024-02-21T15:21:52","modified_gmt":"2024-02-21T14:21:52","slug":"eina-cooperativa-temps-lliure-transformador","status":"publish","type":"post","link":"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/","title":{"rendered":"Eina Cooperativa, temps lliure transformador"},"content":{"rendered":"\n\n<div class=\"wp-block-bancaetica-blocks-blocks-block-49\">\n    <div class=\"container-block-49\">\n\n        <div class=\"header-section \">\n                            <h1 class=\"section-title\"> Etica e cooperativa <\/h1>\n                                            <\/div>\n\n        \n        <div class=\"block-background\" style=\"background-image: url('https:\/\/www.fiarebancaetica.coop\/app\/uploads\/sites\/2\/2023\/12\/eina-cooperativa-temps-lliure-transformador.jpg')\">\n                            <div class=\"tile\">\n                    <h1 class=\"image-title\"> Eina Cooperativa, temps lliure transformador <\/h1>\n                <\/div>             <!-- end .tile -->\n            <div class=\"bottom-content\">\n                            <\/div> <!-- end .button-content -->\n        <\/div> <!-- end .block-background -->\n    <\/div> <!-- end .container -->\n<\/div> <!-- end wp-block-bancaetica-blocks-blocks-block-06 -->\n\n\n<div class=\"wrapper-crispybacon-class wrapper-crispybacon-class-boxed \">\n    <p>L\u2019Eina \u00e9s una cooperativa que treballa per a la inclusi\u00f3 social i laboral de les persones en risc d\u2019exclusi\u00f3. Dins les activitats que desenvolupen, l\u2019Educaci\u00f3 en el lleure recull aquelles activitats adre\u00e7ades a la comunitat educativa, tant a les fam\u00edlies i les AFA com als centres: Activitats d\u2019educaci\u00f3 en el lleure i de vacances escolars, gesti\u00f3 de menjadors escolars\u2026<\/p>\n<p>El seu comprom\u00eds social els fa \u00e9sser conscients de les necessitats socials, cada cop m\u00e9s complexes i dif\u00edcils d\u2019atendre, que poden portar a les persones a situacions de precarietat socioecon\u00f2mica. Per aix\u00f2 volen contribuir al desenvolupament social sostenible de les persones, entitats i territoris amb els que hi treballen.<\/p>\n<h2>\n\tD&#8217;on neix la idea d&#8217;Eina cooperativa?<\/h2>\n<p>A partir de l\u2019experi\u00e8ncia i la reflexi\u00f3 d\u2019un grup de persones en relaci\u00f3 a les limitacions en el treball comunitari i les dificultats per a donar donar resposta a les necessitats socioecon\u00f2miques de les persones en situaci\u00f3 de risc d\u2019exclusi\u00f3 social. Al mateix temps, es volia generar una alternativa laboral que no estigu\u00e9s vinculada al mercat laboral habitual, caracteritzada per la precarietat a la que aboca aquestes persones.<\/p>\n<h2>\n\tQuins s\u00f3n els objectius i les l\u00ednies de treball de l&#8217;entitat?<\/h2>\n<p>Som una cooperativa sense \u00e0nim de lucre que t\u00e9 com objecte social la inserci\u00f3 sociolaboral de les persones en risc d\u2019exclusi\u00f3. Per a poder assolir aquest objectiu desenvolupem activitats socioeducatives i d\u2019atenci\u00f3 social, com a via de generaci\u00f3 d\u2019ocupaci\u00f3 i de disposar de recursos per a l\u2019impuls de nous projectes dins del marc de l\u2019Economia Social i Solid\u00e0ria que, al sou torn, siguin generadors de llocs de feina amb condicions adequades.<\/p>\n<h2>\n\tCom us ha afectat la crisi de la Covid i com ho esteu gestionant?<\/h2>\n<p>Donada la naturalesa dels nostres serveis, que es presten en el major dels casos en centres educatius i c\u00edvics, ha tingut un efecte devastador, amb una reducci\u00f3 de prop del 90% de la nostra activitat. Aix\u00f2 ens ha obligat a realitzar un ERTO, que ha afectat al 65% de les persones que treballem a la cooperativa, a m\u00e9s a m\u00e9s de generar una important tensi\u00f3 de tresoreria i la necessitat de sol\u00b7licitar un pr\u00e9stec. Per \u00faltim, s\u2019ha produ\u00eft un important volum de p\u00e8rdues, que es previsible que arribin als 80.000 \u20ac al final de juny.<\/p>\n<p>Per tal de pal\u00b7liar els efectes m\u00e9s immediats, especialment pel retard en el cobrament de l\u2019atur per part de les persones afectades per l\u2019ERTO, hem ofert la possibilitat de rebre un cobrament avan\u00e7at de la prestaci\u00f3 per ajudar a minorar els possibles problemes de pagament.<\/p>\n<p>Al mateix temps, hem comen\u00e7at a preparar serveis nous i a revisar els projectes existents, amb l\u2019objectiu doble de poder reprendre l\u2019activitat amb m\u00e9s diversificaci\u00f3, i de tenir m\u00e9s capacitat en la gesti\u00f3 dels serveis que ja oferim, partint de l\u2019impacte de la crisi econ\u00f2mica i les dificultats que tindran moltes fam\u00edlies per a fer front al futur.<\/p>\n<h2>\n\tGestioneu dues cases de col\u00f2nies i diferents casals d&#8217;estiu, com es presenta aquesta temporada?<\/h2>\n<p>Hem estat treballant per tal de poder oferir les activitats d\u2019estiu. Aix\u00f2 ens ha suposat una feina intensa de re-definici\u00f3 dels Serveis i adaptaci\u00f3 a la nova situaci\u00f3, amb l\u2019esperan\u00e7a que finalment es puguin realitzar. Ens preocupa no obstant les dificultats que podem trobar i les incerteses que s\u2019estan produint, per\u00f2 la nostra aposta \u00e9s poder fer activitats, no nom\u00e9s per q\u00fcestions econ\u00f2miques sin\u00f3 especialment perqu\u00e8 entenem<br \/>\n\tque s\u00f3n molt necess\u00e0ries per als infants i que, independentment de les circumst\u00e0ncies en que es realitzen les activitats (distanciament social, equip de protecci\u00f3 individual, sempre ser\u00e0 una alternativa per a que els infants puguin re-trobar-se i anar superant poc a poc la situaci\u00f3.<\/p>\n<h2>\n\tQuines s\u00f3n les vostres perspectives de futur?<\/h2>\n<p>Mirem de ser el m\u00e9s positius possible, tot i que tampoc volem caure en voluntarismes; si b\u00e9 \u00e9s cert que aquesta crisi pot marcar difer\u00e8ncies en quant a la valoraci\u00f3 social de les tasques de cura i socioeducatives, la situaci\u00f3 econ\u00f2mica suposar\u00e0 un fre important a una transici\u00f3 \u2013 m\u00e9s que mai necess\u00e0ria \u2013 en qu\u00e8 aquestes tasques es vegin com una inversi\u00f3 i no com fins ara que, molt sovint, han estat vistes com una despesa i associades a situacions de precarietat.<\/p>\n<p>Precisament per aix\u00f2, tamb\u00e9 creiem que hem de continuar aposant pel nostre model, treballant des de la qualitat i amb una perspectiva social transformadora, i confiem que podrem mantenir i augmentar el nostre volum d\u2019activitat: contestant la pregunta, veiem un futur complicat i incert, de contracci\u00f3, i que far\u00e0 m\u00e9s necess\u00e0ria que mai la pr\u00e0ctica dels valors de solidaritat i cooperaci\u00f3 que defensem, per\u00f2 que obre possibilitats tant a nivell intern, en la millora dels nostres processos, funcionament i adaptaci\u00f3 per a poder continuar oferint la mateixa qualitat amb menys recursos, com extern, en poder explorar noves alternatives i models en les activitats que oferim.<\/p>\n<h2>\n\tPer qu\u00e8 heu decidit treballar amb un banc com Fiare Banca Etica?<\/h2>\n<p>Des dels nostres inicis hem apostat per la Economia Social i Solid\u00e0ria. Aix\u00f2 s\u2019ha reflectit en el treball amb entitats i empreses d\u2019ESS en la mesura que la situaci\u00f3 de solv\u00e8ncia de la cooperativa ens ho ha anat permetent. En aquest sentit, feia molt de temps que contemplaven la necessitat de treballar amb una entitat que ofer\u00eds serveis bancaris en sentit estricte, ja que entenem que \u00e9s un sector estrat\u00e8gic si reialment volem que l\u2019ESS<br \/>\n\ttingui un impacte real i pronunciat, amb l\u2019extensi\u00f3 d\u2019un model obert al conjunt de la societat. Per aix\u00f2, en el moment que hem tingut l\u2019oportunitat de treballar amb Fiare, ho hem fet.<\/p>\n<h2>\n\tImpulseu altres projectes comunitaris i d&#8217;econom\u00eda social. \u00bfQuines sinergies creieu que us aporta el treball en xarxa?<\/h2>\n<p>El treball en xarxa \u00e9s, per a nosaltres, tant un necessitat com una aposta estrat\u00e8gica. \u00c9s una necessitat en quant que creiem que \u00e9s la millor manera d\u2019impulsar nousprojectes, en l\u00ednia amb els nostres objectius socials, projectes que a m\u00e9s a m\u00e9s tinguin una major capacitat transformadora. I \u00e9s una aposta estrat\u00e8gica en tant que \u00e9s el nostre model de creixement, un model que ha d\u2019estar basat en el creixement enxarxat d\u2019una pluralitat d\u2019entitats, el que garanteix l\u2019orientaci\u00f3 als valors de l\u2019ESS i evita\/minora l\u2019orientaci\u00f3 al mercat que, molt sovint, \u00e9s necess\u00e0ria a partir d\u2019un volum determinat d\u2019activitat.<\/p>\n<p>Sabem per pr\u00f2pia experi\u00e8ncia que \u00e9s un model ple de dificultats, que suposa coordinar una pluralitat de visions i interessos molts sovint diferents, per\u00f2 \u00e9s precisament en aquesta pluralitat on podem extreure de forma conjunta nous aprenentatges, idees i possibilitats, amb un enriquiment mutu de les entitats que participem.<\/p>\n<p><a href=\"http:\/\/www.einacooperativa.coop\"><strong>www.einacooperativa.coop<\/strong><\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Eina cooperativa neix a partir de l\u2019experi\u00e8ncia i la reflexi\u00f3 d\u2019un grup de persones en relaci\u00f3 a les limitacions en el treball comunitari i les dificultats per a donar donar resposta a les necessitats socioecon\u00f2miques de les persones en situaci\u00f3 de risc d\u2019exclusi\u00f3 social. Al mateix temps, es volia generar una alternativa laboral que no estigu\u00e9s vinculada al mercat laboral habitual, caracteritzada per la precarietat a la que aboca aquestes persones.<\/p>\n<p>Quins s\u00f3n els objectius i les l\u00ednies de treball de l&#8217;entitat?<\/p>\n","protected":false},"author":2,"featured_media":329215,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11644],"tags":[],"coauthors":[],"class_list":["post-344273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finantza-etikoak"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eina Cooperativa, temps lliure transformador - Fiare Banca Etica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/\" \/>\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eina Cooperativa, temps lliure transformador - Fiare Banca Etica\" \/>\n<meta property=\"og:description\" content=\"Eina cooperativa neix a partir de l\u2019experi\u00e8ncia i la reflexi\u00f3 d\u2019un grup de persones en relaci\u00f3 a les limitacions en el treball comunitari i les dificultats per a donar donar resposta a les necessitats socioecon\u00f2miques de les persones en situaci\u00f3 de risc d\u2019exclusi\u00f3 social. Al mateix temps, es volia generar una alternativa laboral que no estigu\u00e9s vinculada al mercat laboral habitual, caracteritzada per la precarietat a la que aboca aquestes persones. Quins s\u00f3n els objectius i les l\u00ednies de treball de l&#039;entitat?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiare Banca Etica\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-26T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-21T14:21:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiarebancaetica.coop\/app\/uploads\/sites\/2\/2023\/12\/eina-cooperativa-temps-lliure-transformador.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"crispyadmin0\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/\"},\"author\":{\"name\":\"crispyadmin0\",\"@id\":\"https:\/\/www.fiarebancaetica.coop\/eu\/#\/schema\/person\/579841e89c804b5db05d9141bd9b8272\"},\"headline\":\"Eina Cooperativa, temps lliure transformador\",\"datePublished\":\"2020-05-26T22:00:00+00:00\",\"dateModified\":\"2024-02-21T14:21:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/\"},\"wordCount\":1182,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiarebancaetica.coop\/app\/uploads\/sites\/2\/2023\/12\/eina-cooperativa-temps-lliure-transformador.jpg\",\"articleSection\":[\"Finantza etikoak\"],\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/\",\"url\":\"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/\",\"name\":\"Eina Cooperativa, temps lliure transformador - Fiare Banca Etica\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiarebancaetica.coop\/eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiarebancaetica.coop\/app\/uploads\/sites\/2\/2023\/12\/eina-cooperativa-temps-lliure-transformador.jpg\",\"datePublished\":\"2020-05-26T22:00:00+00:00\",\"dateModified\":\"2024-02-21T14:21:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.fiarebancaetica.coop\/eu\/#\/schema\/person\/579841e89c804b5db05d9141bd9b8272\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/#primaryimage\",\"url\":\"https:\/\/www.fiarebancaetica.coop\/app\/uploads\/sites\/2\/2023\/12\/eina-cooperativa-temps-lliure-transformador.jpg\",\"contentUrl\":\"https:\/\/www.fiarebancaetica.coop\/app\/uploads\/sites\/2\/2023\/12\/eina-cooperativa-temps-lliure-transformador.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiarebancaetica.coop\/eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eina Cooperativa, temps lliure transformador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiarebancaetica.coop\/eu\/#website\",\"url\":\"https:\/\/www.fiarebancaetica.coop\/eu\/\",\"name\":\"Fiare Banca Etica\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiarebancaetica.coop\/eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiarebancaetica.coop\/eu\/#\/schema\/person\/579841e89c804b5db05d9141bd9b8272\",\"name\":\"crispyadmin0\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\/\/www.fiarebancaetica.coop\/eu\/#\/schema\/person\/image\/5f3a6b7786f32f4c35bd2b1a5a4698ea\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4d2cfb499d497b6d49da659fab7404b243a87fe8e40d2cf97a1cae48f677f5b2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4d2cfb499d497b6d49da659fab7404b243a87fe8e40d2cf97a1cae48f677f5b2?s=96&d=mm&r=g\",\"caption\":\"crispyadmin0\"},\"sameAs\":[\"crispyadmin0\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eina Cooperativa, temps lliure transformador - Fiare Banca Etica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/","og_locale":"eu_ES","og_type":"article","og_title":"Eina Cooperativa, temps lliure transformador - Fiare Banca Etica","og_description":"Eina cooperativa neix a partir de l\u2019experi\u00e8ncia i la reflexi\u00f3 d\u2019un grup de persones en relaci\u00f3 a les limitacions en el treball comunitari i les dificultats per a donar donar resposta a les necessitats socioecon\u00f2miques de les persones en situaci\u00f3 de risc d\u2019exclusi\u00f3 social. Al mateix temps, es volia generar una alternativa laboral que no estigu\u00e9s vinculada al mercat laboral habitual, caracteritzada per la precarietat a la que aboca aquestes persones. Quins s\u00f3n els objectius i les l\u00ednies de treball de l'entitat?","og_url":"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/","og_site_name":"Fiare Banca Etica","article_published_time":"2020-05-26T22:00:00+00:00","article_modified_time":"2024-02-21T14:21:52+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/www.fiarebancaetica.coop\/app\/uploads\/sites\/2\/2023\/12\/eina-cooperativa-temps-lliure-transformador.jpg","type":"image\/jpeg"}],"author":"crispyadmin0","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/#article","isPartOf":{"@id":"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/"},"author":{"name":"crispyadmin0","@id":"https:\/\/www.fiarebancaetica.coop\/eu\/#\/schema\/person\/579841e89c804b5db05d9141bd9b8272"},"headline":"Eina Cooperativa, temps lliure transformador","datePublished":"2020-05-26T22:00:00+00:00","dateModified":"2024-02-21T14:21:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/"},"wordCount":1182,"commentCount":0,"image":{"@id":"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiarebancaetica.coop\/app\/uploads\/sites\/2\/2023\/12\/eina-cooperativa-temps-lliure-transformador.jpg","articleSection":["Finantza etikoak"],"inLanguage":"eu","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/","url":"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/","name":"Eina Cooperativa, temps lliure transformador - Fiare Banca Etica","isPartOf":{"@id":"https:\/\/www.fiarebancaetica.coop\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/#primaryimage"},"image":{"@id":"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiarebancaetica.coop\/app\/uploads\/sites\/2\/2023\/12\/eina-cooperativa-temps-lliure-transformador.jpg","datePublished":"2020-05-26T22:00:00+00:00","dateModified":"2024-02-21T14:21:52+00:00","author":{"@id":"https:\/\/www.fiarebancaetica.coop\/eu\/#\/schema\/person\/579841e89c804b5db05d9141bd9b8272"},"breadcrumb":{"@id":"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/#primaryimage","url":"https:\/\/www.fiarebancaetica.coop\/app\/uploads\/sites\/2\/2023\/12\/eina-cooperativa-temps-lliure-transformador.jpg","contentUrl":"https:\/\/www.fiarebancaetica.coop\/app\/uploads\/sites\/2\/2023\/12\/eina-cooperativa-temps-lliure-transformador.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiarebancaetica.coop\/eu\/eina-cooperativa-temps-lliure-transformador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiarebancaetica.coop\/eu\/"},{"@type":"ListItem","position":2,"name":"Eina Cooperativa, temps lliure transformador"}]},{"@type":"WebSite","@id":"https:\/\/www.fiarebancaetica.coop\/eu\/#website","url":"https:\/\/www.fiarebancaetica.coop\/eu\/","name":"Fiare Banca Etica","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiarebancaetica.coop\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Person","@id":"https:\/\/www.fiarebancaetica.coop\/eu\/#\/schema\/person\/579841e89c804b5db05d9141bd9b8272","name":"crispyadmin0","image":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.fiarebancaetica.coop\/eu\/#\/schema\/person\/image\/5f3a6b7786f32f4c35bd2b1a5a4698ea","url":"https:\/\/secure.gravatar.com\/avatar\/4d2cfb499d497b6d49da659fab7404b243a87fe8e40d2cf97a1cae48f677f5b2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d2cfb499d497b6d49da659fab7404b243a87fe8e40d2cf97a1cae48f677f5b2?s=96&d=mm&r=g","caption":"crispyadmin0"},"sameAs":["crispyadmin0"]}]}},"_links":{"self":[{"href":"https:\/\/www.fiarebancaetica.coop\/eu\/wp-json\/wp\/v2\/posts\/344273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiarebancaetica.coop\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiarebancaetica.coop\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiarebancaetica.coop\/eu\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiarebancaetica.coop\/eu\/wp-json\/wp\/v2\/comments?post=344273"}],"version-history":[{"count":2,"href":"https:\/\/www.fiarebancaetica.coop\/eu\/wp-json\/wp\/v2\/posts\/344273\/revisions"}],"predecessor-version":[{"id":354598,"href":"https:\/\/www.fiarebancaetica.coop\/eu\/wp-json\/wp\/v2\/posts\/344273\/revisions\/354598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fiarebancaetica.coop\/eu\/wp-json\/wp\/v2\/media\/329215"}],"wp:attachment":[{"href":"https:\/\/www.fiarebancaetica.coop\/eu\/wp-json\/wp\/v2\/media?parent=344273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiarebancaetica.coop\/eu\/wp-json\/wp\/v2\/categories?post=344273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiarebancaetica.coop\/eu\/wp-json\/wp\/v2\/tags?post=344273"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.fiarebancaetica.coop\/eu\/wp-json\/wp\/v2\/coauthors?post=344273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}